{"id":3433,"date":"2020-12-07T14:48:28","date_gmt":"2020-12-07T17:48:28","guid":{"rendered":"http:\/\/academiadebeats.com.br\/blog\/?p=3433"},"modified":"2021-01-11T18:08:34","modified_gmt":"2021-01-11T21:08:34","slug":"microfone-condensador-para-homestudio-qual-comprar-2020","status":"publish","type":"post","link":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/","title":{"rendered":"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021"},"content":{"rendered":"<h1>QUAL O MELHOR MICROFONE CONDENSADOR PROFISSIONAL DE HOMESTUDIO?<\/h1>\n<p>&nbsp;<\/p>\n<p>O <strong>microfone condensador de homestudio<\/strong>\u00a0\u00e9 <strong>mais sens\u00edvel<\/strong> para a <strong>capta\u00e7\u00e3o de \u00e1udio<\/strong> do que o <strong>microfone din\u00e2mico<\/strong> (muito <strong>usado em shows<\/strong>), deixando assim, a grava\u00e7\u00e3o com a <em>qualidade maior<\/em>.<\/p>\n<p>Alguns produtores optam por usar <strong>microfone din\u00e2mico no home studio<\/strong>, por ele <strong>n\u00e3o captar detalhes externos indesejados<\/strong> (principalmente quando o <strong>local de grava\u00e7\u00e3o<\/strong> \u00e9 <strong>muito barulhento<\/strong>).<\/p>\n<p>Por\u00e9m, isso acaba implicando numa <strong>perda de qualidade da grava\u00e7\u00e3o<\/strong>.<\/p>\n<p>Independentemente da sua escolha, \u00e9 <em>essencial lembrar<\/em> que <strong>O MELHOR EQUIPAMENTO \u00c9 O QUE VOC\u00ca TEM EM M\u00c3OS<\/strong>. O\u00a0<strong>CONHECIMENTO<\/strong> <strong>\u00e9 a chave<\/strong> para <strong>te levar onde voc\u00ea quiser!<\/strong><\/p>\n<p>Durante o processo de escolha, <strong>al\u00e9m do pre\u00e7o<\/strong> a ser analisado (principalmente com a<strong> alta do d\u00f3lar<\/strong>), <strong>\u00e9 essencial que<\/strong>, ao fazer a compra, <strong>voc\u00ea saiba o que est\u00e1 adquirindo<\/strong>.<\/p>\n<p>E para te mostrar <strong>tudo que voc\u00ea precisa se atentar, nesse momento de escolha<\/strong> do seu microfone condensador, fizemos um <strong>GUIA PR\u00c1TICO pra te nortear<\/strong>. Se liga:<\/p>\n<p>&nbsp;<\/p>\n<h2>1- OR\u00c7AMENTO<\/h2>\n<p>Antes de tudo, aconselhamos que voc\u00ea <strong>tenha um pre\u00e7o m\u00e1ximo<\/strong>, que <em><strong>caiba no seu or\u00e7amento<\/strong><\/em>, <em><strong>independentemente de qual for<\/strong><\/em> ele.<\/p>\n<p>Trabalhar com uma faixa de valores, <strong>j\u00e1 vai te direcionar bastante no processo de escolha<\/strong> do seu microfone condensador.<\/p>\n<p><strong><a href=\"https:\/\/academiadebeats.com.br\/blog\/como-montar-seu-home-studio\/\" target=\"_blank\" rel=\"noopener noreferrer\">SE LIGA NESSAS 9 DICAS PARA MONTAR O SEU HOME STUDIO<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2>2- DURABILIDADE DO MICROFONE CONDENSADOR<\/h2>\n<p>Um <strong>microfone profissional de home studio \u00e9 algo sens\u00edvel, principalmente \u00e0 quedas<\/strong>.<\/p>\n<p>Por isso, \u00e9 importante que voc\u00ea escolha um microfone que tenha uma <strong>boa estrutura<\/strong>, que n\u00e3o seja fr\u00e1gil.<\/p>\n<p>Os <strong>modelos mais baratos<\/strong>, normalmente s\u00e3o <strong>abertos facilmente, apenas desrosqueando<\/strong>, tornando-os <strong>mais vulner\u00e1veis e sens\u00edveis<\/strong>.<\/p>\n<p>Perceba tamb\u00e9m o <strong>material usado nele<\/strong> (normalmente <strong>pl\u00e1stico ou metal<\/strong>), pois isso faz toda <strong>diferen\u00e7a<\/strong> na quest\u00e3o de <strong>durabilidade<\/strong>, pois claro, o <strong>pl\u00e1stico \u00e9 mais fr\u00e1gil<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2>3- PRESS\u00c3O SONORA (SPL)<\/h2>\n<p>Todo <strong>microfone<\/strong> tem uma <strong>Press\u00e3o Sonora M\u00e1xima (SPL)<\/strong>, ou seja, a <strong>press\u00e3o sonora que ele suporta, sem distorcer o \u00e1udio<\/strong>.<\/p>\n<p><strong>Analise a<\/strong> <strong>SPL<\/strong> das op\u00e7\u00f5es <strong>de acordo com o seu objetivo<\/strong>.<\/p>\n<p>Se voc\u00ea quiser <strong>gravar um bumbo de bateria<\/strong>, por exemplo, a <strong>press\u00e3o sonora m\u00e1xima<\/strong> deve ser <strong>maior do que um usado apenas para grava\u00e7\u00e3o de voz<\/strong>.<\/p>\n<p>E mesmo que seja somente voz, \u00e9 muito importante que voc\u00ea <strong>tenha um pop-filter<\/strong>, para <strong>eliminar a acidez sonora (sibil\u00e2ncia)<\/strong> em letras como <strong>&#8220;p&#8221; e &#8220;b&#8221;, &#8220;s&#8221; e &#8220;x&#8221;<\/strong>.<\/p>\n<p>Mas, normalmente, ele \u00e9 um <strong>acess\u00f3rio vendido separadamente<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-3447 size-large\" src=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-1024x683.jpg\" alt=\"pop-filter-ajuda-a-tirar-a-sibilancia-da-gravacao-de-voz\" width=\"750\" height=\"500\" srcset=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-1024x683.jpg 1024w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-300x200.jpg 300w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-768x512.jpg 768w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-1536x1024.jpg 1536w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-2048x1365.jpg 2048w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-360x240.jpg 360w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jason-rosewell-ASKeuOZqhYU-unsplash-600x400.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p><strong><a href=\"http:\/\/academiadebeats.com.br\/blog\/como-gravar-vocais-em-casa-de-forma-profissional-5-dicas\/\" target=\"_blank\" rel=\"noopener noreferrer\">COMO GRAVAR VOCAIS EM CASA DE FORMA PROFISSIONAL<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2>4- ACESS\u00d3RIOS<\/h2>\n<p><strong>Os itens que v\u00eam junto do microfone costumam variar de modelo pra modelo<\/strong>.<\/p>\n<p>Normalmente, ele vem ao menos com um <strong>estojo protetor<\/strong>, para <strong>n\u00e3o ter problemas com transporte<\/strong>, caso queira lev\u00e1-lo para algum lugar.<\/p>\n<p>Mas, alguns podem vir com: <strong>aranha (sistema anti-choque), suporte, adaptador<\/strong>, e dependendo do kit, <strong>pedestal, adaptador de rosca, pop-filter, cabo<\/strong>, etc.<\/p>\n<p>Mesmo que eles n\u00e3o venham no kit, <em><strong>voc\u00ea precisar\u00e1 de alguns desses itens, dependendo do seu tipo de uso<\/strong><\/em>.<\/p>\n<p>Por isso, ao comprar o seu microfone condensador, <strong>analise os acess\u00f3rios que v\u00eam junto de cada op\u00e7\u00e3o<\/strong>, pra entender qual compensa mais financeiramente.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-3450 size-medium aligncenter\" src=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-225x300.jpg\" alt=\"microfone-condensador\" width=\"225\" height=\"300\" srcset=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-225x300.jpg 225w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-768x1024.jpg 768w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-1152x1536.jpg 1152w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-1536x2048.jpg 1536w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/kate-oseen-XqLQxSUuEXQ-unsplash-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>5- PADR\u00c3O POLAR DO SEU MICROFONE CONDENSADOR<\/h2>\n<p>Existem alguns <strong>tipos de capta\u00e7\u00e3o<\/strong>, chamados de <strong>padr\u00f5es polares<\/strong>. Para escolher o seu microfone, \u00e9 indispens\u00e1vel que voc\u00ea leve o que tem o <strong>melhor padr\u00e3o polar para sua demanda de uso<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-3458 aligncenter\" src=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/padroes-polares.jpg\" alt=\"padroes-polares-microfone-condensador\" width=\"560\" height=\"142\" srcset=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/padroes-polares.jpg 560w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/padroes-polares-300x76.jpg 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><em><strong>Omni<\/strong><\/em>: <em>captam o som em 360\u00b0<\/em>, ou seja, tudo que est\u00e1 a sua volta. \u00c9 <strong>\u00f3timo para usos espec\u00edficos<\/strong>, como na <strong>grava\u00e7\u00e3o de coros<\/strong>, mas, como ele <strong>n\u00e3o elimina nenhum &#8220;som indesejado&#8221;<\/strong>, n\u00e3o \u00e9 t\u00e3o recomendado para home studio;<\/li>\n<li><em><strong>Figura 8<\/strong><\/em>: eles <em>captam o som de tudo que est\u00e1 a frente e atr\u00e1s do microfone, excluindo os lados.<\/em> S\u00e3o muito \u00fateis para para <strong>gravar duas pessoas<\/strong>;<\/li>\n<li><em><strong>Cardi\u00f3ide<\/strong><\/em>: <em>capta o som em uma dire\u00e7\u00e3o<\/em>, <strong>excluindo a regi\u00e3o atr\u00e1s dela<\/strong>;<\/li>\n<li><em><strong>Super\/Hiper Cardi\u00f3ide<\/strong><\/em>:<em> tem a \u00e1rea de capta\u00e7\u00e3o mais reduzida do que o Cardi\u00f3ide<\/em>, mas <strong>acabam captando a regi\u00e3o logo atr\u00e1s da c\u00e1psula<\/strong>.<\/li>\n<\/ul>\n<p>Para um<em><strong> home studio<\/strong><\/em>, o <strong><em>Cardi\u00f3ide<\/em><\/strong> ou o <strong>Super Cardi\u00f3ide<\/strong> s\u00e3o os <strong>mais recomendados<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2>6- A C\u00c1PSULA DO SEU MICROFONE CONDENSADOR<\/h2>\n<p>O <strong>microfone condensador transforma a energia sonora em el\u00e9trica<\/strong>, atrav\u00e9s do <strong>movimento<\/strong> que o <strong>diafragma<\/strong> executa ao sofrer uma <strong>press\u00e3o sonora<\/strong>.<\/p>\n<p>O <strong><em>diafragma se movimenta de acordo com a &#8220;flexibilidade&#8221; que a c\u00e1psula permite<\/em><\/strong> a ele.<\/p>\n<p>Existem <strong>3 tipos de c\u00e1psulas<\/strong>:<\/p>\n<ul>\n<li><strong><em>Pequena<\/em>:<\/strong> tem um <em>design mais fino e cil\u00edndrico<\/em>, feitos para <strong>aguentar press\u00f5es sonoras maiores<\/strong>, ideais para <strong>grava\u00e7\u00f5es de viol\u00e3o e pratos da bateria<\/strong>.<br \/>\nSeus <strong>pontos negativos<\/strong> est\u00e3o relacionados ao <strong>ru\u00eddo maior<\/strong> e a <strong>sensibilidade menor<\/strong> na capta\u00e7\u00e3o de detalhes, devido \u00e0 sua <strong>c\u00e1psula mais r\u00edgida<\/strong>, que segura mais o movimento do diafragma;<\/li>\n<li><strong><em>M\u00e9dia<\/em>:<\/strong> s\u00e3o h\u00edbridos, por terem <strong>sensibilidade parecida com a de um microfone de c\u00e1psula larga<\/strong>, mantendo <strong>o brilho dos agudos, que os de c\u00e1psula pequena tem<\/strong>;<\/li>\n<li><strong><em>Grande<\/em>:<\/strong> quanto <strong>maior for a c\u00e1psula<\/strong> do microfone condensador, <strong>mais facilmente o diafragma se movimentar\u00e1<\/strong> e<strong>\u00a0mais detalhes sonoros<\/strong> do ambiente ser\u00e3o captados.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-3449\" src=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-1024x683.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-1024x683.jpg 1024w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-300x200.jpg 300w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-768x512.jpg 768w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-1536x1024.jpg 1536w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-2048x1365.jpg 2048w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-360x240.jpg 360w, https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jk-sloan-a2U_k9AZXJY-unsplash-600x400.jpg 600w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>7- CONECTOR DE SA\u00cdDA<\/h2>\n<p>Se atente ao <strong>conector de sa\u00edda do microfone<\/strong>, pois isso influencia na <strong>qualidade da capta\u00e7\u00e3o<\/strong>.<\/p>\n<p>Voc\u00ea vai verificar que existem desde as <em><strong>entradas XLR (qualidade maior) at\u00e9 USB (qualidade menor)<\/strong><\/em>.<\/p>\n<p>&nbsp;<\/p>\n<h2>8- RU\u00cdDO<\/h2>\n<p>Por mais que sejam m\u00ednimos e <strong>quase impercept\u00edveis<\/strong>, ainda assim v\u00e3o existir ru\u00eddos no seu microfone condensador.<\/p>\n<p>Por isso, \u00e9 importante <em><strong>verificar a quantidade de ru\u00eddo sonoro gerado pela capta\u00e7\u00e3o<\/strong><\/em> do seu microfone condensador, atrav\u00e9s das <strong>especifica\u00e7\u00f5es t\u00e9cnicas<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Agora que j\u00e1 sabe no que voc\u00ea deve ficar de olho para comprar o seu microfone condensador, fa\u00e7a a sua pesquisa e <strong>escolha o melhor microfone para voc\u00ea<\/strong>: <em><strong>O QUE VOC\u00ca PUDER COMPRAR<\/strong><\/em>.<\/p>\n<p>N\u00e3o esque\u00e7a: <em><strong>EQUIPAMENTO NENHUM FAZ MILAGRE<\/strong><\/em>.<\/p>\n<p>Independentemente do pre\u00e7o e at\u00e9 mesmo <strong><em>se voc\u00ea pode ou n\u00e3o comprar<\/em><\/strong> um no momento, <strong>sem CONHECIMENTO para gravar e tratar a grava\u00e7\u00e3o<\/strong>, voc\u00ea n\u00e3o chega \u00e0 qualidade profissional.<\/p>\n<p>Por isso, <strong>n\u00e3o seja ref\u00e9m de equipamento algum<\/strong>!<\/p>\n<p>&nbsp;<\/p>\n<h2><strong><a href=\"https:\/\/www.instagram.com\/p\/CIOpWtLgZD5\/\" target=\"_blank\" rel=\"noopener noreferrer\">SE LIGA NESSA VIS\u00c3O DO DJ COALA SOBRE GRAVA\u00c7\u00c3O DE VOZ!<\/a><\/strong><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>QUAL O MELHOR MICROFONE CONDENSADOR PROFISSIONAL DE HOMESTUDIO? &nbsp; O microfone condensador de homestudio\u00a0\u00e9 mais sens\u00edvel para a capta\u00e7\u00e3o de \u00e1udio do que o microfone din\u00e2mico (muito usado em shows), deixando assim, a grava\u00e7\u00e3o com a qualidade maior. Alguns produtores optam por usar microfone din\u00e2mico no home studio, por ele n\u00e3o captar detalhes externos indesejados [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3451,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog<\/title>\n<meta name=\"description\" content=\"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\u00ea escolher o seu e n\u00e3o se arrepender!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog\" \/>\n<meta property=\"og:description\" content=\"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\u00ea escolher o seu e n\u00e3o se arrepender!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Academia de Beats - Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/academiadebeats\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-07T17:48:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-11T21:08:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Djalma Andrade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/#website\",\"url\":\"https:\/\/academiadebeats.com.br\/blog\/\",\"name\":\"Academia de Beats - Blog\",\"description\":\"Aqui \\u00e9 o blog do Beatmaker\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/academiadebeats.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg\",\"contentUrl\":\"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"microfone-condensador-de-home-studio\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#webpage\",\"url\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/\",\"name\":\"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#primaryimage\"},\"datePublished\":\"2020-12-07T17:48:28+00:00\",\"dateModified\":\"2021-01-11T21:08:34+00:00\",\"author\":{\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/#\/schema\/person\/964569fd9498d0a314675891afedb067\"},\"description\":\"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\\u00ea escolher o seu e n\\u00e3o se arrepender!\",\"breadcrumb\":{\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/academiadebeats.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/#\/schema\/person\/964569fd9498d0a314675891afedb067\",\"name\":\"Djalma Andrade\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/academiadebeats.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e196d2f806676eb839c8f5f92c0366d8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e196d2f806676eb839c8f5f92c0366d8?s=96&d=mm&r=g\",\"caption\":\"Djalma Andrade\"},\"url\":\"https:\/\/academiadebeats.com.br\/blog\/author\/djalma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog","description":"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\u00ea escolher o seu e n\u00e3o se arrepender!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/","og_locale":"pt_BR","og_type":"article","og_title":"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog","og_description":"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\u00ea escolher o seu e n\u00e3o se arrepender!","og_url":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/","og_site_name":"Academia de Beats - Blog","article_publisher":"https:\/\/www.facebook.com\/academiadebeats\/","article_published_time":"2020-12-07T17:48:28+00:00","article_modified_time":"2021-01-11T21:08:34+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary","twitter_misc":{"Escrito por":"Djalma Andrade","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/academiadebeats.com.br\/blog\/#website","url":"https:\/\/academiadebeats.com.br\/blog\/","name":"Academia de Beats - Blog","description":"Aqui \u00e9 o blog do Beatmaker","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/academiadebeats.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg","contentUrl":"https:\/\/academiadebeats.com.br\/blog\/wp-content\/uploads\/2019\/04\/jonathan-velasquez-c1ZN57GfDB0-unsplash-scaled.jpg","width":2560,"height":1707,"caption":"microfone-condensador-de-home-studio"},{"@type":"WebPage","@id":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#webpage","url":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/","name":"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021 - Academia de Beats - Blog","isPartOf":{"@id":"https:\/\/academiadebeats.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#primaryimage"},"datePublished":"2020-12-07T17:48:28+00:00","dateModified":"2021-01-11T21:08:34+00:00","author":{"@id":"https:\/\/academiadebeats.com.br\/blog\/#\/schema\/person\/964569fd9498d0a314675891afedb067"},"description":"Qual o melhor microfone condensador para homestudio? Se liga nesse post onde preparamos um guia para voc\u00ea escolher o seu e n\u00e3o se arrepender!","breadcrumb":{"@id":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/academiadebeats.com.br\/blog\/microfone-condensador-para-homestudio-qual-comprar-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/academiadebeats.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"MICROFONE CONDENSADOR PARA HOMESTUDIO 2021"}]},{"@type":"Person","@id":"https:\/\/academiadebeats.com.br\/blog\/#\/schema\/person\/964569fd9498d0a314675891afedb067","name":"Djalma Andrade","image":{"@type":"ImageObject","@id":"https:\/\/academiadebeats.com.br\/blog\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/e196d2f806676eb839c8f5f92c0366d8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e196d2f806676eb839c8f5f92c0366d8?s=96&d=mm&r=g","caption":"Djalma Andrade"},"url":"https:\/\/academiadebeats.com.br\/blog\/author\/djalma\/"}]}},"_links":{"self":[{"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/posts\/3433"}],"collection":[{"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3433"}],"version-history":[{"count":23,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/posts\/3433\/revisions"}],"predecessor-version":[{"id":3523,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/posts\/3433\/revisions\/3523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/media\/3451"}],"wp:attachment":[{"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/academiadebeats.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}